{"id":8240,"date":"2024-10-25T21:50:54","date_gmt":"2024-10-25T19:50:54","guid":{"rendered":"https:\/\/www.ladante-linz.at\/?post_type=news&#038;p=8240"},"modified":"2024-11-05T00:10:23","modified_gmt":"2024-11-04T23:10:23","slug":"einladung-zu-75-jahre-dante-alighieri-linz","status":"publish","type":"news","link":"https:\/\/www.ladante-linz.at\/de\/news\/einladung-zu-75-jahre-dante-alighieri-linz\/","title":{"rendered":"Gro\u00ad\u00dfe Jubi\u00adl\u00e4\u00adums\u00adfei\u00ader \u2014 75 Jah\u00adre Socie\u00adt\u00e0 Dan\u00adte Ali\u00adghie\u00adri&nbsp;Linz"},"content":{"rendered":"<p style=\"text-align: center;\">Sehr geehr\u00adte Mitglieder,<br>\nlie\u00adbe Freun\u00addin\u00adnen und Freun\u00adde der Dan\u00adte&nbsp;Linz,<br>\n<em>cari amici e soci del\u00adla&nbsp;Dante,<\/em><\/p>\n<p style=\"text-align: center;\">wir m\u00f6ch\u00adten Sie hier\u00admit herz\u00adlich zu unse\u00adrer <strong>gro\u00ad\u00dfen Jubi\u00adl\u00e4\u00adums\u00adfei\u00ader am Frei\u00adtag, 22. Novem\u00adber 2024 um 18:00 Uhr im Ober\u00adbank Donau-Forum<\/strong> (Unte\u00adre Donau\u00adl\u00e4n\u00adde 28, 4020 Linz) einladen.<br>\nHin\u00adweis: Die Tief\u00adga\u00adra\u00adge ist ab 17:00 Uhr ge\u00f6ffnet.<\/p>\n<p style=\"text-align: center;\">An die\u00adsem Fest\u00adabend m\u00f6ch\u00adten wir gemein\u00adsam mit Ihnen das <strong>75-j\u00e4h\u00adri\u00adge Bestehen der Socie\u00adt\u00e0 Dan\u00adte Ali\u00adghie\u00adri Linz<\/strong> feiern.<br>\nMit Stolz blickt die Socie\u00adt\u00e0 Dan\u00adte Ali\u00adghie\u00adri Linz dabei auf ein Drei\u00advier\u00adtel\u00adjahr\u00adhun\u00addert Geschich\u00adte zur\u00fcck, die wir bei die\u00adser Gele\u00adgen\u00adheit Revue pas\u00adsie\u00adren las\u00adsen. Im Zuge der 75 Jah\u00adre-Fei\u00ader\u00adlich\u00adkei\u00adten erscheint auch eine<strong> Fest\u00adschrift<\/strong>, die Sie an die\u00adsem Abend ger\u00adne als Erin\u00adne\u00adrung mit nach Hau\u00adse neh\u00admen k\u00f6nnen.<\/p>\n<p style=\"text-align: center;\">Nach einem Emp\u00adfang und Gru\u00df\u00adbot\u00adschaf\u00adten erwar\u00adtet Sie ein <strong>bun\u00adter ita\u00adlie\u00adni\u00adscher Abend mit einem gro\u00ad\u00dfen ita\u00adlie\u00adni\u00adschen Buf\u00adfet, einem Ita\u00adli\u00aden\u00adquiz und einer Tom\u00adbo\u00adla<\/strong> mit wert\u00advol\u00adlen Preisen.<\/p>\n<p style=\"text-align: center;\">Musi\u00adka\u00adlisch beglei\u00adten wird die Fei\u00ader das \u201e<strong>Z\u00e0ga\u00adra Express\u201c<\/strong>-Trio, bestehend aus drei S\u00fcd\u00adita\u00adlie\u00adnern (Tizia\u00adno kommt aus Kam\u00adpa\u00adni\u00aden, Gian\u00adni aus Apu\u00adli\u00aden, Sal\u00advo aus Sizi\u00adli\u00aden) mit einer Lei\u00adden\u00adschaft f\u00fcr gute ita\u00adlie\u00adni\u00adsche Musik. Sie las\u00adsen uns an die\u00adsem Abend viel\u00adf\u00e4l\u00adtig in die ita\u00adlie\u00adni\u00adsche Pop\u00admu\u00adsik eintauchen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8230 aligncenter\" src=\"https:\/\/www.ladante-linz.at\/wp-content\/uploads\/2024\/10\/MG_0177-300x200.jpg\" alt=\"Z\u00e0gara Express\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.ladante-linz.at\/wp-content\/uploads\/2024\/10\/MG_0177-300x200.jpg 300w, https:\/\/www.ladante-linz.at\/wp-content\/uploads\/2024\/10\/MG_0177-1024x683.jpg 1024w, https:\/\/www.ladante-linz.at\/wp-content\/uploads\/2024\/10\/MG_0177-768x512.jpg 768w, https:\/\/www.ladante-linz.at\/wp-content\/uploads\/2024\/10\/MG_0177-1536x1024.jpg 1536w, https:\/\/www.ladante-linz.at\/wp-content\/uploads\/2024\/10\/MG_0177-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><\/p>\n<p style=\"text-align: center;\">\u00a9 Z\u00e0ga\u00adra Express<br>\nSal\u00advo, Tizia\u00adno &amp; Gian\u00adni (v. l. n.&nbsp;r.)<\/p>\n<p style=\"text-align: center;\">Wir bit\u00adten um Ihre ver\u00adbind\u00adli\u00adche <strong>Anmel\u00addung bis Frei\u00adtag, 15. Novem\u00adber<\/strong> unter <a href=\"mailto:veranstaltungen.dante@liwest.at\">veranstaltungen.dante@liwest.at<\/a> und<strong> ersu\u00adchen Sie als Mit\u00adglied um \u00dcber\u00adwei\u00adsung eines Unkos\u00adten\u00adbei\u00adtra\u00adges von \u20ac20,- bis 15. Novem\u00adber<\/strong> (Zah\u00adlungs\u00adein\u00adgang), Ver\u00adwen\u00addungs\u00adzweck \u201eJubi\u00adl\u00e4\u00adums\u00adfei\u00ader\u201c.<br>\nKin\u00adder bis 10 Jah\u00adre zah\u00adlen in Beglei\u00adtung \u20ac5,-.<\/p>\n<p style=\"text-align: center;\"><strong>Nicht\u00admit\u00adglie\u00adder<\/strong> bzw. Per\u00adso\u00adnen, die im Jahr 2024 noch kei\u00adnen Mit\u00adglieds\u00adbei\u00adtrag geleis\u00adtet haben, ersu\u00adchen wir um <strong>\u00dcber\u00adwei\u00adsung von \u20ac30,- auf unser Ver\u00adeins\u00adkon\u00adto<\/strong>:<\/p>\n<p style=\"text-align: center;\">Socie\u00adt\u00e0 Dan\u00adte Ali\u00adghie\u00adri&nbsp;Linz<br>\nIBAN: AT94 1500 0007 2160&nbsp;5087<br>\nBIC: OBKLAT2L<\/p>\n<p style=\"text-align: center;\">Dadurch erleich\u00adtern Sie uns und dem Cate\u00adring die Planung.<br>\nHerz\u00adli\u00adchen Dank&nbsp;daf\u00fcr!<\/p>\n<p style=\"text-align: center;\">Wir freu\u00aden uns auf Ihre Teil\u00adnah\u00adme und ein bal\u00addi\u00adges Wiedersehen.<\/p>\n<p style=\"text-align: center;\">Soll\u00adten Sie am Ver\u00adan\u00adstal\u00adtungs\u00adtag ver\u00adhin\u00addert sein, w\u00fcr\u00adden wir uns nat\u00fcr\u00adlich auch \u00fcber eine Spen\u00adde als Bei\u00adtrag zu einer gelun\u00adge\u00adnen Fei\u00ader auf unser Kon\u00adto freuen.<\/p>\n<p style=\"text-align: center;\">Herz\u00adli\u00adche&nbsp;Gr\u00fc\u00dfe<\/p>\n<p style=\"text-align: center;\">Das Team der Dan\u00adte Ali\u00adghie\u00adri&nbsp;Linz<\/p>\n<p style=\"text-align: center;\"><em>Cor\u00addia\u00adli salu\u00adti e a presto!<\/em><\/p>\n<p style=\"text-align: center;\"><em>Il team del\u00adla Dan\u00adte&nbsp;Linz<\/em><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Es wird dar\u00adauf hin\u00adge\u00adwie\u00adsen, dass am Ver\u00adan\u00adstal\u00adtungs\u00adort Fotos und\/oder Vide\u00ados ange\u00adfer\u00adtigt wer\u00adden und zu Zwe\u00adcken des Berichts \u00fcber die\u00adse Ver\u00adan\u00adstal\u00adtung in Print\u00adme\u00addi\u00aden, in News\u00adlet\u00adtern, im Inter\u00adnet, in sozia\u00adlen Medi\u00aden und bei Ver\u00adan\u00adstal\u00adtun\u00adgen ver\u00ad\u00f6f\u00adfent\u00adlicht wer\u00adden bzw. von der Socie\u00adt\u00e0 Dan\u00adte Ali\u00adghie\u00adri Linz frei\u00adge\u00adge\u00adben wer\u00adden k\u00f6nnen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sehr geehr\u00adte Mit\u00adglie\u00adder, lie\u00adbe Freun\u00addin\u00adnen und Freun\u00adde der Dan\u00adte&nbsp;Linz, cari amici e soci del\u00adla&nbsp;Dan\u00adte, wir m\u00f6ch\u00adten Sie hier\u00admit herz\u00adlich zu unse\u00adrer gro\u00ad\u00dfen Jubi\u00adl\u00e4\u00adums\u00adfei\u00ader am Frei\u00adtag, 22. Novem\u00adber 2024 um 18:00 Uhr im Ober\u00adbank Donau-Forum (Unte\u00adre Donau\u00adl\u00e4n\u00adde 28, 4020 Linz) einladen.<\/p>\n","protected":false},"author":3,"featured_media":303,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"news-category":[49],"class_list":["post-8240","news","type-news","status-publish","has-post-thumbnail","hentry","news-category-societa"],"_links":{"self":[{"href":"https:\/\/www.ladante-linz.at\/de\/wp-json\/wp\/v2\/news\/8240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ladante-linz.at\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.ladante-linz.at\/de\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladante-linz.at\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladante-linz.at\/de\/wp-json\/wp\/v2\/comments?post=8240"}],"version-history":[{"count":7,"href":"https:\/\/www.ladante-linz.at\/de\/wp-json\/wp\/v2\/news\/8240\/revisions"}],"predecessor-version":[{"id":8252,"href":"https:\/\/www.ladante-linz.at\/de\/wp-json\/wp\/v2\/news\/8240\/revisions\/8252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ladante-linz.at\/de\/wp-json\/wp\/v2\/media\/303"}],"wp:attachment":[{"href":"https:\/\/www.ladante-linz.at\/de\/wp-json\/wp\/v2\/media?parent=8240"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladante-linz.at\/de\/wp-json\/wp\/v2\/tags?post=8240"},{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.ladante-linz.at\/de\/wp-json\/wp\/v2\/news-category?post=8240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}