{"id":4864,"date":"2021-01-08T23:09:29","date_gmt":"2021-01-08T22:09:29","guid":{"rendered":"https:\/\/www.ladante-linz.at\/?page_id=4864"},"modified":"2022-01-21T22:22:37","modified_gmt":"2022-01-21T21:22:37","slug":"teilnahme-an-der-generalversammlung","status":"publish","type":"page","link":"https:\/\/www.ladante-linz.at\/it\/teilnahme-an-der-generalversammlung\/","title":{"rendered":"Par\u00adti\u00adci\u00adpa\u00adzio\u00adne all\u2019As\u00adsem\u00adblea ple\u00adna\u00adria 2022 \u2014 online"},"content":{"rendered":"<div class=\"ce-header\">\n<h2 class=\"h1\">TEILNAHME AN DER ONLINE-GENERALVERSAMMLUNG 2022<\/h2>\n<p class=\"subtitle\">Die Teil\u00adnah\u00adme ist aus\u00adschlie\u00df\u00adlich Mit\u00adglie\u00addern vorbehalten.<\/p>\n<h5>Frei\u00adtag, 28.01.2022 \u2014 18:00 Uhr \u00fcber&nbsp;Zoom<\/h5>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"ce-textpic ce-center ce-above\">\n<div class=\"ce-bodytext\">\n<h5>1. Anmel\u00addung zur Generalversammlung<\/h5>\n<p>Wir bit\u00adten Sie Ihre <strong>Teil\u00adnah\u00adme <\/strong>an der Gene\u00adral\u00adver\u00adsamm\u00adlung vor\u00adab per E\u2011Mail an <a title=\"kastelruth.stulrich@raiffeisen.it\" href=\"mailto:mitgliedschaft.dante@liwest.at\">mitgliedschaft.dante@liwest.at<\/a> an.<\/p>\n<p>&nbsp;<\/p>\n<h5>2. Regis\u00adtrie\u00adrung bei&nbsp;Zoom<\/h5>\n<p><span class=\"ILfuVd NA6bn\"><span class=\"hgKElc\">Sie k\u00f6n\u00adnen zwar auch ohne spe\u00adzi\u00adel\u00adle Soft\u00adware \u00fcber Ihren Web-Brow\u00adser teil\u00adneh\u00admen,<\/span><\/span> eine Regis\u00adtrie\u00adrung und Instal\u00adla\u00adti\u00adon der Soft\u00adware ist jedoch empfehlenswert.<\/p>\n<p>Um an der Video\u00adkon\u00adfe\u00adrenz teil\u00adneh\u00admen zu k\u00f6n\u00adnen, m\u00fcs\u00adsen Sie sich vor\u00adab als Nut\u00adzer&nbsp;auf der Platt\u00adform&nbsp;<strong>ZOOM&nbsp;<\/strong>(<strong><a title=\"https:\/\/zoom.us\" href=\"https:\/\/zoom.us\/\" target=\"_blank\" rel=\"noopener\">https:\/\/zoom.us<\/a><\/strong>) kos\u00adten\u00adlos registrieren.<\/p>\n<p>Die Regis\u00adtrie\u00adrung und auch die Nut\u00adzung des Sys\u00adtems ist mit\u00adtels Smart\u00adphone, Tablet, Note\u00adbook oder PC (sofern mit Web\u00adcam und Mikro\u00adfon aus\u00adge\u00adstat\u00adtet) m\u00f6g\u00adlich. Bit\u00adte neh\u00admen Sie die Regis\u00adtrie\u00adrung bereits eini\u00adge Tage vor der Gene\u00adral\u00adver\u00adsamm\u00adlung vor und machen Sie sich mit dem Sys\u00adtem vertraut.<\/p>\n<p>&nbsp;<\/p>\n<h5>3. Instal\u00adla\u00adti\u00adon der Software<\/h5>\n<p>Neh\u00admen Sie die Instal\u00adla\u00adti\u00adon der Soft\u00adware auf dem Ger\u00e4t vor, mit wel\u00adchem Sie an der Video\u00adkon\u00adfe\u00adrenz teil\u00adneh\u00admen werden.<\/p>\n<p style=\"padding-left: 40px;\">- Auf einem <strong>PC <\/strong>laden Sie sich die kos\u00adten\u00adlo\u00adse Soft\u00adware \u201eZoom-Cli\u00adent f\u00fcr Mee\u00adtings\u201c unter fol\u00adgen\u00addem Link her\u00adun\u00adter: <a href=\"https:\/\/zoom.us\/download\" target=\"_blank\" rel=\"noopener\">https:\/\/zoom.us\/download<\/a><\/p>\n<p style=\"padding-left: 40px;\">- Auf einem Smartphone\/Tablet mit <strong>Android <\/strong>laden Sie sich die kos\u00adten\u00adlo\u00adse Zoom-App aus dem Goog\u00adle Play Store: <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=us.zoom.videomeetings\" target=\"_blank\" rel=\"noopener\">https:\/\/play.google.com\/store\/apps\/details?id=us.zoom.videomeetings<\/a><\/p>\n<p style=\"padding-left: 40px;\">- Auf einem Smartphone\/Tablet mit <strong>iOS <\/strong>laden Sie sich die kos\u00adten\u00adlo\u00adse Zoom-App aus dem App Store: <a href=\"https:\/\/apps.apple.com\/us\/app\/zoom-cloud-meetings\/id546505307\" target=\"_blank\" rel=\"noopener\">https:\/\/apps.apple.com\/us\/app\/zoom-cloud-meetings\/id546505307<\/a><\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"ce-textpic ce-center ce-above\">\n<div class=\"ce-bodytext\">\n<h5>4. Tech\u00adni\u00adsche Voraussetzungen<\/h5>\n<p style=\"padding-left: 40px;\">- F\u00fcr die Video\u00adkon\u00adfe\u00adrenz ist eine funk\u00adtio\u00adnie\u00adren\u00adde <strong>Web\u00adcam <\/strong>Vor\u00adaus\u00adset\u00adzung. F\u00fcr die Teil\u00adnah\u00adme an der Video\u00adkon\u00adfe\u00adrenz muss&nbsp;die\u00adse ein\u00adge\u00adschal\u00adten&nbsp;sein.<\/p>\n<p style=\"padding-left: 40px;\">- <strong>Laut\u00adspre\u00adcher <\/strong>oder <strong>Kopf\u00adh\u00f6\u00adrer<\/strong> damit Sie der Pr\u00e4\u00adsen\u00adta\u00adti\u00adon fol\u00adgen\u00adden k\u00f6nnen.<\/p>\n<p style=\"padding-left: 40px;\">- Ein <strong>Mikro\u00adfon&nbsp;<\/strong>ist f\u00fcr eine evtl. Fra\u00adge\u00adstel\u00adlung empfehlenswert.<\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"ce-textpic ce-center ce-above\">\n<div class=\"ce-bodytext\">\n<h5>5. Ein\u00adtritt zur Videokonferenz<\/h5>\n<p>Damit wir sie recht\u00adzei\u00adtig zur Video\u00adkon\u00adfe\u00adrenz ein\u00adlas\u00adsen k\u00f6n\u00adnen, bit\u00adten wir Sie bereits <strong>10 Minu\u00adten vor der Gene\u00adral\u00adver\u00adsamm\u00adlung<\/strong>, die Anwen\u00addung Zoom zu star\u00adten und der Video\u00adkon\u00adfe\u00adrenz bei\u00adzu\u00adtre\u00adten. <span class=\"d2edcug0 hpfvmrgz qv66sw1b c1et5uql oi732d6d ik7dh3pa fgxwclzu a8c37x1j keod5gw0 nxhoafnm aigsh9s9 d3f4x2em fe6kdd0r mau55g9w c8b282yb iv3no6db jq4qci2q a3bd9o3v knj5qynh oo9gr5id\" dir=\"auto\">Wir w\u00fcr\u00adden Sie dabei bit\u00adten, Ihre Mikro\u00adfo\u00adne aus\u00adzu\u00adschal\u00adten. Da offe\u00adne Mikros st\u00f6\u00adrend wir\u00adken k\u00f6n\u00adnen, wird der Mode\u00adra\u00adtor die Mikros schlie\u00ad\u00dfen, soll\u00adten sie offen&nbsp;sein.<\/span><\/p>\n<p>&nbsp;<\/p>\n<div class=\"ce-textpic ce-center ce-above\">\n<div class=\"ce-bodytext\">\n<h5>6. Wort\u00admel\u00addun\u00adgen w\u00e4h\u00adrend der Videokonferenz<\/h5>\n<p>M\u00f6ch\u00adten Sie sich zu Wort mel\u00adden, k\u00f6n\u00adnen Sie direkt auf \u201eReak\u00adtio\u00adnen\u201c in der unte\u00adren Leis\u00adte kli\u00adcken und hier auf das gel\u00adbe Sym\u00adbol mit dem Wort\u00adlaut \u201e<strong>Hand heben<\/strong>\u201c. Wir wer\u00adden Ihnen anschlie\u00ad\u00dfend das Mikro\u00adfon freischalten.<\/p>\n<p>&nbsp;<\/p>\n<h5>7. Unter\u00adst\u00fct\u00adzung vor und w\u00e4h\u00adrend der Generalversammlung<\/h5>\n<p>F\u00fcr tech\u00adni\u00adsche Unter\u00adst\u00fct\u00adzung vor und w\u00e4h\u00adrend der Gene\u00adral\u00adver\u00adsamm\u00adlung sind wir per E\u2011Mail erreich\u00adbar unter <a href=\"mailto:dante.linz@liwest.at\">dante.linz@liwest.at<\/a>.<br>\nAu\u00dfer\u00addem k\u00f6n\u00adnen Sie sich w\u00e4h\u00adrend der Video\u00adkon\u00adfe\u00adrenz \u00fcber den inte\u00adgrier\u00adten Chat Fra\u00adgen stellen.<br>\nKli\u00adcken Sie daf\u00fcr direkt auf \u201eChat\u201c in der unte\u00adren Leiste.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>TEILNAHME AN DER ONLINE-GENERALVERSAMMLUNG 2022 Die Teil\u00adnah\u00adme ist aus\u00adschlie\u00df\u00adlich Mit\u00adglie\u00addern vor\u00adbe\u00adhal\u00adten. Frei\u00adtag, 28.01.2022 \u2014 18:00 Uhr \u00fcber&nbsp;Zoom &nbsp; 1. Anmel\u00addung zur Gene\u00adral\u00adver\u00adsamm\u00adlung Wir bit\u00adten Sie Ihre Teil\u00adnah\u00adme an der Gene\u00adral\u00adver\u00adsamm\u00adlung vor\u00adab per E\u2011Mail an mitgliedschaft.dante@liwest.at an. &nbsp; 2. Regis\u00adtrie\u00adrung bei&nbsp;Zoom<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":""},"class_list":["post-4864","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ladante-linz.at\/it\/wp-json\/wp\/v2\/pages\/4864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ladante-linz.at\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ladante-linz.at\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladante-linz.at\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladante-linz.at\/it\/wp-json\/wp\/v2\/comments?post=4864"}],"version-history":[{"count":3,"href":"https:\/\/www.ladante-linz.at\/it\/wp-json\/wp\/v2\/pages\/4864\/revisions"}],"predecessor-version":[{"id":5648,"href":"https:\/\/www.ladante-linz.at\/it\/wp-json\/wp\/v2\/pages\/4864\/revisions\/5648"}],"wp:attachment":[{"href":"https:\/\/www.ladante-linz.at\/it\/wp-json\/wp\/v2\/media?parent=4864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}